{"id":2425,"date":"2021-10-08T09:42:22","date_gmt":"2021-10-08T08:42:22","guid":{"rendered":"https:\/\/ccoorenault.es\/?p=2425"},"modified":"2022-02-02T20:00:44","modified_gmt":"2022-02-02T19:00:44","slug":"la-verdad-ofende","status":"publish","type":"post","link":"https:\/\/ccoo.app\/renault\/la-verdad-ofende\/","title":{"rendered":"LA VERDAD OFENDE"},"content":{"rendered":"<p style=\"text-align: justify\"><strong>CCOO<\/strong> comprobamos c\u00f3mo la verdad puede escocer, tanto que hace perder los papeles a una \u201corganizaci\u00f3n sindical\u201d como CGT que, al no tener argumentos, ante una evidencia tan obvia de, si se <strong>les hubiese hecho caso<\/strong>, <strong>ahora deber\u00edamos afrontar la negociaci\u00f3n de un convenio en mitad de un ERTE y de una crisis mundial de semiconductores<\/strong>, cambia la literatura de su comunicado y se pasa al insulto, las amenazas.\u2026 <strong>\u00bfSe os acabaron las ideas?<\/strong><\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Tras esos insultos y amenazas, no nos queda m\u00e1s remedio que contestar, quedando muy claro que, <strong>la principal preocupaci\u00f3n para CCOO es la actual situaci\u00f3n de incertidumbre por la que estamos atravesando<\/strong> y que, parece ser, se puede alargar en el tiempo durante el a\u00f1o 2022. Esa es nuestra prioridad y, no si a la CGT le sienta mal o no nuestra gesti\u00f3n sindical.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Os vamos <strong>a dar unos datos<\/strong>:<\/p>\n<p style=\"text-align: justify\">\n<ul style=\"text-align: justify\">\n<li><strong>CCOO firmamos el ERTE de COVID en marzo de 2020<\/strong>, donde <strong>nuestra prioridad<\/strong> fue preservar la salud de tod@s (en una situaci\u00f3n desconocida para tod@s). La <strong>contestaci\u00f3n de CGT fue que NO<\/strong>, que quer\u00edais dinero, eso s\u00ed, fuisteis los \u00faltimos en saliros del ERTE, cuando los trabajador@s volvimos a los puestos de trabajo, <strong>vosotros dec\u00edais que se atentaba contra la salud, que era una irresponsabilidad retomar la actividad y que se ten\u00eda que seguir de ERTE (ojo a esto).<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify\">\n<ul style=\"text-align: justify\">\n<li><strong>CCOO propone denunciar el convenio (septiembre 2020). <\/strong>CGT en todas las provincias al un\u00edsono \u201cmismo punto de vista que el de sus socios de gobierno UGT y SCP, NO DENUNCIAR el convenio\u201d.<\/li>\n<\/ul>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<ul style=\"text-align: justify\">\n<li><strong>CCOO<\/strong> <strong>firma el Convenio Colectivo<\/strong> con productos para todas las factor\u00edas que garantizan nuestros centros de trabajo, m\u00e1s all\u00e1 del plan de reestructuraci\u00f3n del grupo Renault. CGT <strong>discrepa de la nueva paga individual<\/strong>, que se cobra este mes y dem\u00e1s lindezas.<\/li>\n<\/ul>\n<p style=\"text-align: justify\">\n<ul style=\"text-align: justify\">\n<li><strong>CCOO firma los ERTE por la crisis de semiconductores<\/strong>, que de no haber habido acuerdo se hubiese aplicado un 70% de nuestro salario, no generando ni vacaciones ni pagas extras <strong>y<\/strong> <strong>de lo<\/strong> <strong>que<\/strong> <strong>vosotr@s os benefici\u00e1is. <\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify\">\n<ul style=\"text-align: justify\">\n<li><strong>CCOO<\/strong> trabajamos con las subcontratas y filiales para crear bolsas de horas, ertes y medidas que ayuden a paliar la crisis de semiconductores. No vemos inter\u00e9s alguno a ninguna secci\u00f3n sindical al respecto. Hoy en d\u00eda seguimos igual. Casos de empresas de ingenier\u00eda, mantenimiento, limpieza, comedor, etc\u2026.<\/li>\n<\/ul>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><strong>CCOO con los compa\u00f1eros afectados de Sevilla<\/strong>. Hemos estado en todo momento con ellos, desde el minuto cero, incluso con afiliados de otros sindicatos que nos preguntaron nuestra postura y punto de vista ante tan desagradable situaci\u00f3n en la que se encontraban y que, explicaremos m\u00e1s pronto que tarde. Hemos puesto a disposici\u00f3n de cualquier compa\u00f1ero los servicios jur\u00eddicos de CCOO, que en todo momento han estado ayudando a quienes han querido nuestra ayuda, y que seguimos apoyando, asesorando y acompa\u00f1ando a d\u00eda de hoy. Nuestros servicios jur\u00eddicos son conocidos en todos los \u00e1mbitos de lo laboral, comprometidos y profesionales, a lo mejor otros no pueden decir lo mismo.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Por otro lado, todav\u00eda estamos esperando que <strong>CGT<\/strong> nos expliqu\u00e9is <strong>la convocatoria de huelga fantasma en Sevilla<\/strong>, que presentasteis en solitario a primeros de agosto y que, ni siquiera lo comentasteis en los comit\u00e9s de empresa, al igual que las acciones que hab\u00e9is realizado en la factor\u00eda (muy loables por vuestra parte), otra vez sin proponerlas en el comit\u00e9, pero donde se han escuchado muchas mentiras, y que casualidad, con la inquina hacia CCOO, sin referencias a vuestros socios de UGT y SCP, record\u00e1ndoos, sin maldad, las veces que hab\u00e9is venido a nuestra secci\u00f3n sindical de SEVILLA para \u201cquitar al comit\u00e9 de empresa de Sevilla actual\u201d que vosotros solitos hab\u00e9is permitido que se creasen en todas las provincias, entendiendo que a la secci\u00f3n sindical de CGT de Sevilla \u201clas c\u00fapulas de vuestro sindicato\u201d callaron o llamaron al orden para defender las mismas posturas de UGT y SCP (inaudito en la historia de RENAULT ESPA\u00d1A), por eso y otras actitudes, en la vida cre\u00edamos en CCOO escuchar palabras como <strong>\u201c\u00cddem o la misma postura que UGT\u201d<\/strong>, y no han sido ni una ni dos veces.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Por ello, os contestamos que, <strong>en nuestras gestiones, lecciones las justas<\/strong>, por que ya hablaremos de la nefasta gesti\u00f3n que est\u00e1is haciendo vosotros en los comit\u00e9s (presidencias, secretarias de salud laboral, de ritmos, etc), totalmente lesiva para los trabajador@s.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Y por \u00faltimos, y no m\u00e1s sorprendente, nos llama la atenci\u00f3n c\u00f3mo insult\u00e1is a <strong>CCOO<\/strong>, culp\u00e1ndonos de todo, pero ni una referencia al<strong> \u00faltimo fichaje de la empresa, delegad@ sindical que ha pasado de defender los derechos de los trabajador@s a defender los derechos de la empresa, <\/strong>quiz\u00e1 tendr\u00e1 que ver con vuestro pacto post-electoral para conseguir vuestros silloncitos en los comit\u00e9s de empresa. Como no puede ser de otra manera, a la espera de otra absurda contestaci\u00f3n\u2026pero recordad:<\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>El tiempo pone a cada uno en su sitio, solo hay que esperar\u2026.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>A TODA LA PLANTILLA DE RENAULT ESPA\u00d1A, sentimos el bochornoso espect\u00e1culo que es vivir un enfrentamiento entre dos o m\u00e1s secciones sindicales, cuando el fin deber\u00eda ser com\u00fan, pero es que llega un momento que uno no puede seguir aguantando mentiras, insultos, vejaciones, y un largo etc\u00e9tera, sobre todo a iguales que, se desviven por defender a sus semejantes. No sabemos que no entiende CGT de UNIDAD O UN\u00c1NIME, que nos los expliquen. <\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>Con estas actitudes solo consiguen que el que gane siga siendo el mismo\u2026\u2026<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u201cHablan mal de nosotr@s. Normal, nunca supieron hablar bien\u201d.<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify\"><strong>\u201cEn CCOO nos hacemos responsables de lo que decimos, decidimos, acordamos, debatimos, defendemos, solucionamos, luchamos y escribimos, no de lo que CGT pueda interpretar\u201d<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/ccoo.app\/renault\/wp-content\/blogs.dir\/6\/files\/sites\/147\/2021\/11\/la-verdad-ofende.pdf\">La VERDAD OFENDE<\/a>    \t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CCOO comprobamos c\u00f3mo la verdad puede escocer, tanto que hace perder los papeles a una \u201corganizaci\u00f3n sindical\u201d como CGT que, al no tener argumentos, ante una evidencia tan obvia de, &#8230; <a title=\"LA VERDAD OFENDE\" class=\"read-more\" href=\"https:\/\/ccoo.app\/renault\/la-verdad-ofende\/\" aria-label=\"Leer m\u00e1s sobre LA VERDAD OFENDE\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5275,"featured_media":2416,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,22,46,47,48],"tags":[],"class_list":["post-2425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-app-push-renault-madrid","category-app-push-renault-palencia","category-app-push-renault-sevilla","category-app-push-renault-valladolid","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"_links":{"self":[{"href":"https:\/\/ccoo.app\/renault\/wp-json\/wp\/v2\/posts\/2425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccoo.app\/renault\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccoo.app\/renault\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccoo.app\/renault\/wp-json\/wp\/v2\/users\/5275"}],"replies":[{"embeddable":true,"href":"https:\/\/ccoo.app\/renault\/wp-json\/wp\/v2\/comments?post=2425"}],"version-history":[{"count":1,"href":"https:\/\/ccoo.app\/renault\/wp-json\/wp\/v2\/posts\/2425\/revisions"}],"predecessor-version":[{"id":2808,"href":"https:\/\/ccoo.app\/renault\/wp-json\/wp\/v2\/posts\/2425\/revisions\/2808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccoo.app\/renault\/wp-json\/wp\/v2\/media\/2416"}],"wp:attachment":[{"href":"https:\/\/ccoo.app\/renault\/wp-json\/wp\/v2\/media?parent=2425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccoo.app\/renault\/wp-json\/wp\/v2\/categories?post=2425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccoo.app\/renault\/wp-json\/wp\/v2\/tags?post=2425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}