{"id":89593,"date":"2025-09-07T19:19:22","date_gmt":"2025-09-07T17:19:22","guid":{"rendered":"https:\/\/ccoo.app\/fundesplai\/?p=89593"},"modified":"2025-09-07T19:19:24","modified_gmt":"2025-09-07T17:19:24","slug":"11-preguntes-frequents-sobre-la-feina-de-les-vetlladores","status":"publish","type":"post","link":"https:\/\/ccoo.app\/fundesplai\/11-preguntes-frequents-sobre-la-feina-de-les-vetlladores\/","title":{"rendered":"11 preguntes freq\u00fcents sobre la feina de les Vetlladores"},"content":{"rendered":"\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>1<\/td><td><strong>Qui determina les hores de suport que hi ha a cada centre?<\/strong>\u00a0<\/td><td>Les hores venen determinades per cada servei territorial en funci\u00f3 de les peticions de cada direcci\u00f3\u00a0<\/td><\/tr><tr><td>2<\/td><td><strong>A qui li correspon distribuir les hores de cada centre i fer els horaris?<\/strong><\/td><td>Aquesta tasca \u00e9s exclusiva de l\u2019empresa. \u00a0<\/td><\/tr><tr><td>3<\/td><td><strong>Si d\u2019un curs respecte a l&#8217;anterior perdo hores, tinc dret a que m\u2019indemnitzin?\u00a0<\/strong><\/td><td>Si, cada any CCOO negocia l\u2019aplicaci\u00f3 de l\u2019article 41 de l\u2019ET que implica el cobrament d\u2019una indemnitzaci\u00f3 per les hores perdudes\u00a0<\/td><\/tr><tr><td>4<\/td><td><strong>El centre em pot modificar l\u2019horari o la jornada?\u00a0<\/strong><\/td><td>No, aix\u00f2 nom\u00e9s ho pot fer l\u2019empresa. De manera motivada, per escrit, i amb 15 dies d&#8217;antelaci\u00f3\u00a0<\/td><\/tr><tr><td>5<\/td><td><strong>Estic obligada a anar a les sortides?<\/strong><\/td><td>Nom\u00e9s si coincideixen amb la totalitat del meu horari\u00a0<\/td><\/tr><tr><td>6<\/td><td><strong>Estic obligada a anar de col\u00f2nies?<\/strong><\/td><td>No<\/td><\/tr><tr><td>7<\/td><td><strong>A qui li haig de comunicar que haig de gaudir d\u2019un perm\u00eds remunerat?<\/strong><\/td><td>A l\u2019empresa mitjan\u00e7ant el portal del treballador i comunicaci\u00f3 a la t\u00e8cnica<\/td><\/tr><tr><td>8<\/td><td><strong>Haig de recuperar els permisos?<\/strong><\/td><td>No, el permisos legalment reconeguts no s\u2019han de recuperar<\/td><\/tr><tr><td>9<\/td><td><strong>Haig de donar suport a qualsevol infant que determini el centre?<\/strong><\/td><td>No, nom\u00e9s haig de donar suport als infants que tenen hores assignades<\/td><\/tr><tr><td>10<\/td><td><strong>Puc quedar-me sola al c\u00e0rrec dels infants NESE?<\/strong><\/td><td>No, en cap cas, tampoc a l\u2019espai del migdia.<\/td><\/tr><tr><td>11<\/td><td><strong>Haig de realitzar informes i\/o mem\u00f2ries?<\/strong><\/td><td>No, no has de fer cap feina fora del teu horari<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2025\/09\/FAQS-Vetlladores.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustaci\u00f3 del fitxer FAQS Vetlladores.\"><\/object><a id=\"wp-block-file--media-90a384b5-b40c-46dd-ac25-68d80be85b6a\" href=\"https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2025\/09\/FAQS-Vetlladores.pdf\">FAQS Vetlladores<\/a><a href=\"https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2025\/09\/FAQS-Vetlladores.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-90a384b5-b40c-46dd-ac25-68d80be85b6a\">Baixa<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>1 Qui determina les hores de suport que hi ha a cada centre?\u00a0 Les hores venen determinades per cada servei territorial en funci\u00f3 de les peticions de cada direcci\u00f3\u00a0 2 &#8230; <a title=\"11 preguntes freq\u00fcents sobre la feina de les Vetlladores\" class=\"read-more\" href=\"https:\/\/ccoo.app\/fundesplai\/11-preguntes-frequents-sobre-la-feina-de-les-vetlladores\/\" aria-label=\"M\u00e9s informaci\u00f3 sobre 11 preguntes freq\u00fcents sobre la feina de les Vetlladores\">Read more<\/a><\/p>\n","protected":false},"author":2677,"featured_media":89594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[155,154,1,152],"tags":[206],"class_list":["post-89593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualitat","category-sabiesque","category-sin-categoria","category-vetlladors","tag-vetlladores","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"_links":{"self":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts\/89593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/users\/2677"}],"replies":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/comments?post=89593"}],"version-history":[{"count":2,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts\/89593\/revisions"}],"predecessor-version":[{"id":89598,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts\/89593\/revisions\/89598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/media\/89594"}],"wp:attachment":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/media?parent=89593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/categories?post=89593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/tags?post=89593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}