{"id":89125,"date":"2023-04-28T12:22:08","date_gmt":"2023-04-28T10:22:08","guid":{"rendered":"https:\/\/ccoo.app\/fundesplai\/?p=89125"},"modified":"2023-04-28T12:24:46","modified_gmt":"2023-04-28T10:24:46","slug":"ccoo-aconsegueix-la-inclusio-de-les-pagues-extres-a-lequiparacio-salarial-de-les-ebm-de-sant-andreu-de-la-barca","status":"publish","type":"post","link":"https:\/\/ccoo.app\/fundesplai\/ccoo-aconsegueix-la-inclusio-de-les-pagues-extres-a-lequiparacio-salarial-de-les-ebm-de-sant-andreu-de-la-barca\/","title":{"rendered":"CCOO aconsegueix la inclusi\u00f3 de les pagues extres a l\u2019equiparaci\u00f3 salarial de les EBM de Sant Andreu de la Barca"},"content":{"rendered":"<div class=\"gb-grid-wrapper gb-grid-wrapper-e0d4e6c0\">\n<div class=\"gb-grid-column gb-grid-column-b6c1851c\"><div class=\"gb-container gb-container-b6c1851c\">\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1796\" height=\"1813\" src=\"https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2023\/04\/puny-petit-llapis-transparent.png\" alt=\"Puny Petit Llapis Transparent\" class=\"wp-image-89127\" srcset=\"https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2023\/04\/puny-petit-llapis-transparent.png 1796w, https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2023\/04\/puny-petit-llapis-transparent-297x300.png 297w, https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2023\/04\/puny-petit-llapis-transparent-1014x1024.png 1014w, https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2023\/04\/puny-petit-llapis-transparent-150x150.png 150w, https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2023\/04\/puny-petit-llapis-transparent-768x775.png 768w, https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2023\/04\/puny-petit-llapis-transparent-1522x1536.png 1522w\" sizes=\"auto, (max-width: 1796px) 100vw, 1796px\" \/><\/figure>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-f6260f67\"><div class=\"gb-container gb-container-f6260f67\">\n\n<div style=\"height:66px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-justify\">Avui,  28 d&#8217;abril de 2023, la Direcci\u00f3 General de Fundesplai i un representant del Comit\u00e8 d&#8217;Empresa han traslladat a les tres direccions de les Escoles Bresssol Municipals de Sant Andreu de la Barca, l&#8217;acord segons el qual s&#8217;inclouen les pagues extres en el procediment d&#8217;equiparaci\u00f3 salarial que fixaba el plec de condicions del concurs p\u00fablic.<\/p>\n\n<\/div><\/div>\n<\/div>\n\n\n<p><strong>FETS:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A data 1 de setembre de 2022, la Fundaci\u00f3 Catalana de l\u2019Esplai inicia la gesti\u00f3 de les 3 Escoles Bressol de Sant Andreu de la Barca (EBM el Trenet, EBM Casa Pedemonte i EBM Cavallet) .<\/li>\n\n\n\n<li>Tal i com s\u2019especificava al plec de condicions del concurs p\u00fablic, l\u2019entitat que guanyes el concurs havia d\u2019equiparar les retribucions del personal, en els sous bases, els complements salarials i les jornades en totes les categories laborals amb independ\u00e8ncia del tipus de contracte que les vinculava amb l\u2019empresa, adoptant com a refer\u00e8ncia el major sou brut actual de les afectades, sense tenir en compte les retribucions per antiguitat.<\/li>\n\n\n\n<li>L\u2019entitat va fer efectiva la equiparaci\u00f3 dels salaris i CPP per\u00f2 va considerar que les pagues havien de quedar al marge de la equiparaci\u00f3 per dos motius:\n<ul class=\"wp-block-list\">\n<li>per qu\u00e8 no es recull en l\u2019apartat del plec de manera expressa&nbsp;<\/li>\n\n\n\n<li>la regulaci\u00f3 de les pagues extraordin\u00e0ries establert al conveni col\u00b7lectiu aplicable (Educaci\u00f3n infantil y centros de asistencia) determina que les pagues extraordin\u00e0ries seran equivalents a l\u2019import del salari base m\u00e9s l\u2019import de complement de perfeccionament professional.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>El comit\u00e8 d\u2019empresa trasllada a l\u2019entitat el desacord  amb aquesta situaci\u00f3 i s\u2019obre un proc\u00e9s de negociaci\u00f3.<\/li>\n<\/ul>\n\n\n\n<p><strong>ACORDS<\/strong>:<\/p>\n\n\n\n<p>Totes dues parts acorden incloure les pagues extres en la equiparaci\u00f3 de salaris  i la seva aplicaci\u00f3 retroactiva des de l\u2019inici del servei de la seg\u00fcent manera\u00a0<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Al maig de 2023 cobraran la part proporcional de la paga de desembre de 2022 corresponent al per\u00edode entre setembre i desembre de 2022.<\/li>\n\n\n\n<li>Al juny de 2023 cobraran la paga amb l\u2019increment proporcional des de setembre de 2022 fins a juny de 2023.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" src=\"http:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2023\/04\/acord-sant-andreu-de-la-barca-1024x724.png\" alt=\"Acord Sant Andreu De La Barca\" class=\"wp-image-89126\" srcset=\"https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2023\/04\/acord-sant-andreu-de-la-barca-1024x724.png 1024w, https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2023\/04\/acord-sant-andreu-de-la-barca-300x212.png 300w, https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2023\/04\/acord-sant-andreu-de-la-barca-768x543.png 768w, https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2023\/04\/acord-sant-andreu-de-la-barca-1536x1086.png 1536w, https:\/\/ccoo.app\/fundesplai\/wp-content\/blogs.dir\/6\/files\/sites\/168\/2023\/04\/acord-sant-andreu-de-la-barca-2048x1448.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>FETS: ACORDS: Totes dues parts acorden incloure les pagues extres en la equiparaci\u00f3 de salaris i la seva aplicaci\u00f3 retroactiva des de l\u2019inici del servei de la seg\u00fcent manera\u00a0<\/p>\n","protected":false},"author":2677,"featured_media":89126,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[171,155,180],"tags":[269,202,211,268],"class_list":["post-89125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acords","category-actualitat","category-edinfantil","tag-0-3","tag-acords","tag-actualitat","tag-bressolsintegrals","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"_links":{"self":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts\/89125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/users\/2677"}],"replies":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/comments?post=89125"}],"version-history":[{"count":4,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts\/89125\/revisions"}],"predecessor-version":[{"id":89135,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts\/89125\/revisions\/89135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/media\/89126"}],"wp:attachment":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/media?parent=89125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/categories?post=89125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/tags?post=89125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}