{"id":88123,"date":"2016-11-09T13:57:00","date_gmt":"2016-11-09T12:57:00","guid":{"rendered":"https:\/\/ccoo.app\/fundesplai\/decret-267-2016\/"},"modified":"2022-09-12T10:51:12","modified_gmt":"2022-09-12T08:51:12","slug":"decret-267-2016","status":"publish","type":"post","link":"https:\/\/ccoo.app\/fundesplai\/decret-267-2016\/","title":{"rendered":"Decret 267\/2016"},"content":{"rendered":"<div style=\"clear: both;text-align: center\"><a href=\"https:\/\/2.bp.blogspot.com\/-3k0nZre7vjs\/WCMOb3NCuQI\/AAAAAAAAAG8\/vbDPuT8s-rQqAiRhPu0_2FLQHMHcsjDFwCLcB\/s1600\/cartoon-1099728.jpg\" style=\"clear: left;float: left;margin-bottom: 1em;margin-right: 1em\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"320\" src=\"https:\/\/2.bp.blogspot.com\/-3k0nZre7vjs\/WCMOb3NCuQI\/AAAAAAAAAG8\/vbDPuT8s-rQqAiRhPu0_2FLQHMHcsjDFwCLcB\/s320\/cartoon-1099728.jpg\" width=\"303\"><\/a><\/div>\n<p><span style=\", sans-serif\">El passat dijous 7 de juliol, es va publicar al DOGC el nou<span style=\"color: red\"> Decret 267\/2016<\/span>, de 5 de juliol, que regula les activitats d&#8217;educaci\u00f3 en el lleure.&nbsp;<\/span><br \/>\n<span style=\", sans-serif\">Inclou qualsevol de les activitats organitzades que es duguin a terme amb menors de 18 anys fora de l&#8217;\u00e0mbit familiar i de les compet\u00e8ncies del Departament d&#8217;Ensenyament, sigui quin sigui el moviment, l&#8217;associaci\u00f3, l&#8217;entitat, la instituci\u00f3, administraci\u00f3, l&#8217;empresa privada o la persona f\u00edsica que l&#8217;organitzi<\/span><br \/>\n<span style=\", sans-serif\"><br \/>\n<\/span><span style=\", sans-serif\">Aquest decret va entrar en vigor l\u20191 de novembre del 2016. Introdueix algunes modificacions respecte el seu predecessor (el&nbsp;decret 137\/2003)<\/span><span style=\", sans-serif\">:<\/span><br \/>\n<span style=\", sans-serif\"><br \/>\n<\/span><span style=\", sans-serif\">A m\u00e9s de les activitats de lleure, es regulen activitats esportives, com ara casals esportius, campus, rutes esportives, etc. Tamb\u00e9, equipara el nombre de dirigents i les r\u00e0tios amb els de les activitats de lleure; tot respectant, per\u00f2, les titulacions esportives.<\/span><br \/>\n<span style=\", sans-serif\"><\/span><\/p>\n<ul>\n<li><span style=\", sans-serif\">S\u2019amplia l\u2019abast del decret, incloent les activitats amb infants menors de 3 anys i n\u2019estableix unes r\u00e0tios espec\u00edfiques.<\/span><\/li>\n<li><span style=\", sans-serif\">Modifica les r\u00e0tios de nens\/es per monitor\/a, establint l\u2019obligatorietat que hi hagi sempre un m\u00ednim de 2 dirigents i deixant un marge de 4 nens\/es abans no sigui obligatori ampliar el nombre de monitors\/es. i augmenta el nombre de persones de l\u2019equip dirigent que ha de tenir titulaci\u00f3.<\/span><\/li>\n<li><span style=\", sans-serif\">Es crear\u00e0 el Registre Oficial de Professionals de l\u2019Educaci\u00f3 en el Lleure de Catalunya, on ser\u00e0 imprescindible estar inscrit de cara a acreditar el fet de disposar de la titulaci\u00f3 necess\u00e0ria per comptabilitzar com a monitor\/a titulat. Tamb\u00e9, hi ha un registre similar per als Professionals de l\u2019Esport.<\/span><\/li>\n<\/ul>\n<p><span style=\"background-color: white;font-family: verdana, sans-serif\">la Direcci\u00f3 General de Joventut organitza una <\/span><b style=\"background-color: white;font-family: verdana, sans-serif\"><span style=\"color: red\">Jornada&nbsp;Formativa sobre el Decret 267\/2016<\/span><\/b><span style=\"background-color: white;font-family: verdana, sans-serif\">&nbsp;oberta a tot&nbsp;el sector, per tal d&#8217;explicar amb detall el contingut del nou Decret i&nbsp;resoldre els dubtes que puguin sorgir.<\/span><\/p>\n<div style=\"background-color: white;margin-bottom: 1em\"><span style=\", sans-serif\">La jornada ser\u00e0 el dimecres, 16\/11\/2016, a les 18.00h, a la seu de la&nbsp;Direcci\u00f3 General de Joventut (c\/ Cal\u00e0bria, 147 08015 Barcelona)<\/span><\/div>\n<div style=\"background-color: white;margin-bottom: 1em\"><span style=\", sans-serif\">La jornada \u00e9s gratu\u00efta per\u00f2, per motius d&#8217;aforament, cal fer la inscripci\u00f3<br \/>\npr\u00e8via al seg\u00fcent enlla\u00e7&nbsp;<a data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=ca&amp;q=http:\/\/bit.ly\/JornadaNOUDecretActivitats&amp;source=gmail&amp;ust=1478776847626000&amp;usg=AFQjCNHV8ctxzCSeXndG6IEs3nIlByDAgg\" href=\"http:\/\/bit.ly\/JornadaNOUDecretActivitats\" style=\"color: #1155cc\" target=\"_blank\" rel=\"noopener\">http:\/\/bit.ly\/JornadaNOUDecretActivitats<\/a><\/span><\/div>\n<p><span style=\", sans-serif\"><br \/>\n<\/span><span style=\", sans-serif\"><br \/>\n<\/span><span style=\", sans-serif\"><br \/>\n<\/span><span style=\", sans-serif\">Podeu consultar el nou decret en aquest <a href=\"https:\/\/goo.gl\/YaYzZM\" target=\"_blank\" rel=\"noopener\">enlla\u00e7<\/a>&nbsp;&nbsp;goo.gl\/YaYzZM<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El passat dijous 7 de juliol, es va publicar al DOGC el nou Decret 267\/2016, de 5 de juliol, que regula les activitats d&#8217;educaci\u00f3 en el lleure.&nbsp; Inclou qualsevol de &#8230; <a title=\"Decret 267\/2016\" class=\"read-more\" href=\"https:\/\/ccoo.app\/fundesplai\/decret-267-2016\/\" aria-label=\"M\u00e9s informaci\u00f3 sobre Decret 267\/2016\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[155,161],"tags":[211,203,80,234],"class_list":["post-88123","post","type-post","status-publish","format-standard","hentry","category-actualitat","category-comunicats","tag-actualitat","tag-ccoo","tag-comunicats","tag-lleure","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"_links":{"self":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts\/88123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/comments?post=88123"}],"version-history":[{"count":1,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts\/88123\/revisions"}],"predecessor-version":[{"id":88895,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts\/88123\/revisions\/88895"}],"wp:attachment":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/media?parent=88123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/categories?post=88123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/tags?post=88123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}