{"id":88010,"date":"2021-07-02T10:38:00","date_gmt":"2021-07-02T08:38:00","guid":{"rendered":"https:\/\/ccoo.app\/fundesplai\/acord-per-assegurar-el-sistema-de-pensions\/"},"modified":"2022-07-26T16:12:02","modified_gmt":"2022-07-26T14:12:02","slug":"acord-per-assegurar-el-sistema-de-pensions","status":"publish","type":"post","link":"https:\/\/ccoo.app\/fundesplai\/acord-per-assegurar-el-sistema-de-pensions\/","title":{"rendered":"ACORD PER ASSEGURAR EL SISTEMA DE PENSIONS"},"content":{"rendered":"<p>L&#8217;1 de Juliol CCOO ha signat un acord per tal de garantir el maneteniment del sistema p\u00fablic de pensions.<\/p>\n<div><\/div>\n<div>  L&#8217;acord deroga la malaurada reforma que va fer el PP l&#8217;any 2013 i en garenteix   la revaloritzaci\u00f3 d&#8217;aquestes en funci\u00f3 de l&#8217;IPC. En aquest pacte s&#8217;inclouen   altres mesures com per exemple l\u2019equiparaci\u00f3 de les pensions de vidu\u00eftat de   les parelles de fet, l\u2019extensi\u00f3 del dret de cotitzaci\u00f3 per a tots els   programes de formaci\u00f3 i la millora dels convenis especials per a persones   treballadores de les cures i persones dependents, &#8230;&nbsp;<\/div>\n<div><\/div>\n<div>Podeu llegir la not\u00edcia sencera si cliqueu el seg\u00fcent enlla\u00e7:<\/div>\n<div><\/div>\n<div><\/div>\n<div><a href=\"https:\/\/educaccio.cat\/2021\/educacio\/tot-sobre-lacord-de-pensions-2021\">https:\/\/educaccio.cat\/2021\/educacio\/tot-sobre-lacord-de-pensions-2021<\/a>\/<\/div>\n<div>  <a href=\"https:\/\/educaccio.cat\/2021\/educacio\/tot-sobre-lacord-de-pensions-2021\/\" target=\"_blank\" rel=\"noopener\"><\/a><\/div>\n<div style=\"clear: both\">  <a href=\"https:\/\/1.bp.blogspot.com\/-wwtyx30FROM\/YN7QOq4o1QI\/AAAAAAAABrU\/0sxwEAbFlMEy_6_Qo2kvRfHAbhKATEemACLcBGAsYHQ\/s1754\/Puny%2Bamb%2BSecci%25C3%25B3%2BSindical_page-0001.jpg\" style=\"padding: 1em 0px;text-align: center\"><img decoding=\"async\" alt=\"\" border=\"0\" data-original-height=\"1754\" data-original-width=\"1241\" height=\"600\" src=\"https:\/\/1.bp.blogspot.com\/-wwtyx30FROM\/YN7QOq4o1QI\/AAAAAAAABrU\/0sxwEAbFlMEy_6_Qo2kvRfHAbhKATEemACLcBGAsYHQ\/s600\/Puny%2Bamb%2BSecci%25C3%25B3%2BSindical_page-0001.jpg\"><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;1 de Juliol CCOO ha signat un acord per tal de garantir el maneteniment del sistema p\u00fablic de pensions. L&#8217;acord deroga la malaurada reforma que va fer el PP l&#8217;any &#8230; <a title=\"ACORD PER ASSEGURAR EL SISTEMA DE PENSIONS\" class=\"read-more\" href=\"https:\/\/ccoo.app\/fundesplai\/acord-per-assegurar-el-sistema-de-pensions\/\" aria-label=\"M\u00e9s informaci\u00f3 sobre ACORD PER ASSEGURAR EL SISTEMA DE PENSIONS\">Read more<\/a><\/p>\n","protected":false},"author":6,"featured_media":88449,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[155],"tags":[202,203,204],"class_list":["post-88010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualitat","tag-acords","tag-ccoo","tag-pensions","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"_links":{"self":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts\/88010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/comments?post=88010"}],"version-history":[{"count":2,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts\/88010\/revisions"}],"predecessor-version":[{"id":88519,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/posts\/88010\/revisions\/88519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/media\/88449"}],"wp:attachment":[{"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/media?parent=88010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/categories?post=88010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccoo.app\/fundesplai\/wp-json\/wp\/v2\/tags?post=88010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}