{"id":987,"date":"2021-02-16T14:40:53","date_gmt":"2021-02-16T13:40:53","guid":{"rendered":"https:\/\/fcc-cornella.ccoo.cat\/?p=987"},"modified":"2021-12-01T20:46:51","modified_gmt":"2021-12-01T19:46:51","slug":"agradecimiento-de-la-empresa-a-trabajadores-as-fcc-cornella-por-la-aportacion-al-banco-de-alimentos","status":"publish","type":"post","link":"https:\/\/ccoo.app\/fcc-cornella\/agradecimiento-de-la-empresa-a-trabajadores-as-fcc-cornella-por-la-aportacion-al-banco-de-alimentos\/","title":{"rendered":"Agradecimiento de la empresa a trabajadores\/as FCC Cornella por la aportaci\u00f3n al banco de alimentos"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/logos-cornella-trasmparente.png\" alt=\"La imagen tiene un atributo ALT vac\u00edo; su nombre de archivo es Logos-Cornella-trasmparente.png\" width=\"63\" height=\"66\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Os ajuntamos la carta que ha escrito el Director general de FCC Medio Ambiente SAU, dirigida a todos los trabajadores de esta contrata, donde expresa su agradecimiento por la aportaci\u00f3n del fondo social que se hizo el a\u00f1o pasado de 1225\u20ac al banco de alimentos <\/p>\n\n\n\n<p>Puedes descargar esta carta\u00a0\u00a0<a href=\"https:\/\/drive.google.com\/file\/d\/1EVi1M0PCPvlgzfNNDpBomFN27PhKWPXM\/view?usp=sharing\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>___EN ESTA PAGINA___<\/strong><\/a><\/p>\n    \t","protected":false},"excerpt":{"rendered":"<p>Os ajuntamos la carta que ha escrito el Director general de FCC Medio Ambiente SAU, dirigida a todos los trabajadores de esta contrata, donde expresa su agradecimiento por la aportaci\u00f3n &#8230; <a title=\"Agradecimiento de la empresa a trabajadores\/as FCC Cornella por la aportaci\u00f3n al banco de alimentos\" class=\"read-more\" href=\"https:\/\/ccoo.app\/fcc-cornella\/agradecimiento-de-la-empresa-a-trabajadores-as-fcc-cornella-por-la-aportacion-al-banco-de-alimentos\/\" aria-label=\"Leer m\u00e1s sobre Agradecimiento de la empresa a trabajadores\/as FCC Cornella por la aportaci\u00f3n al banco de alimentos\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5217,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-987","post","type-post","status-publish","format-standard","hentry","category-fccinfo","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"_links":{"self":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/users\/5217"}],"replies":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/comments?post=987"}],"version-history":[{"count":1,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/987\/revisions"}],"predecessor-version":[{"id":2906,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/987\/revisions\/2906"}],"wp:attachment":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/media?parent=987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/categories?post=987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/tags?post=987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}