{"id":813,"date":"2020-03-18T19:35:52","date_gmt":"2020-03-18T18:35:52","guid":{"rendered":"https:\/\/fcc-cornella.ccoo.cat\/?p=813"},"modified":"2021-12-01T20:47:06","modified_gmt":"2021-12-01T19:47:06","slug":"coronavirus-consultas-telefonica-y-por-internet","status":"publish","type":"post","link":"https:\/\/ccoo.app\/fcc-cornella\/coronavirus-consultas-telefonica-y-por-internet\/","title":{"rendered":"Coronavirus- Consultas telef\u00f3nica y por internet"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-792 alignright\" src=\"http:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/logos-cornella-trasmparente.png\" alt=\"\" width=\"40\" height=\"42\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" id=\"ctl00_ContentPlaceHolder1_noticia1_imgNoticia\" class=\"imagefloatleft\" src=\"https:\/\/www.ccoo.cat\/imatges\/fotos_100_75\/coronavirus_atencio_web_.jpg\" alt=\"Foto\" width=\"275\" height=\"206\" align=\"left\" \/><\/p>\n<p><span style=\"line-height: 1.5\">Estas son las l\u00edneas de acci\u00f3n que ha puesto en marcha CCOO de Catalu\u00f1a para afrontar la crisis del coronavirus, con servicios de atenci\u00f3n telef\u00f3nica (933 100 000) y por internet ( <\/span><a style=\"line-height: 1.5\" href=\"https:\/\/consulta.ccoo.cat\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/consulta.ccoo.cat<\/a><span style=\"line-height: 1.5\"> ): medidas generales , gesti\u00f3n de los conflictos en empresas y asesoramiento para todos,\u00a0<\/span><span style=\"line-height: 1.5\">\u00a0para la protecci\u00f3n laboral de la clase trabajadora y evitar que la gente con menos recursos acabe pagando la recesi\u00f3n econ\u00f3mica que se vislumbra tras la crisis sanitaria.<\/span><\/p>\n<p><span style=\"line-height: 1.5\">La m\u00e1xima prioridad \u00a0es conseguir que los gobiernos promulguen medidas generales para proteger a las personas asalariadas y las que hacen trabajo aut\u00f3nomo. Hay que conseguir que no haya despidos, que todo el mundo cobre a fin de mes y, de manera inmediata, tener medidas de prevenci\u00f3n y conciliaci\u00f3n adecuadas para todas las personas que trabajan en servicios esenciales.\u00a0<\/span><\/p>\n<p><span style=\"line-height: 1.5\">Todo sobre la gesti\u00f3n de ERTE, con el objetivo de evitar despidos y conseguir medidas de reorganizaci\u00f3n interna. La prevenci\u00f3n, con protocolos y productos adecuados, es la m\u00e1xima preocupaci\u00f3n de las trabajadoras y los trabajadores que est\u00e1n trabajando forzosamente porque cubren los servicios esenciales, estrat\u00e9gicos y b\u00e1sicos.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-814 aligncenter\" src=\"https:\/\/fcc-cornella.ccoo.cat\/wp-content\/uploads\/sites\/124\/2020\/03\/Consultas-de-coronavirus-300x212.jpg\" alt=\"\" width=\"300\" height=\"212\" \/><\/p>\n<p>&nbsp;    \t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estas son las l\u00edneas de acci\u00f3n que ha puesto en marcha CCOO de Catalu\u00f1a para afrontar la crisis del coronavirus, con servicios de atenci\u00f3n telef\u00f3nica (933 100 000) y por &#8230; <a title=\"Coronavirus- Consultas telef\u00f3nica y por internet\" class=\"read-more\" href=\"https:\/\/ccoo.app\/fcc-cornella\/coronavirus-consultas-telefonica-y-por-internet\/\" aria-label=\"Leer m\u00e1s sobre Coronavirus- Consultas telef\u00f3nica y por internet\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5217,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-813","post","type-post","status-publish","format-standard","hentry","category-fccinfo","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"_links":{"self":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/users\/5217"}],"replies":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/comments?post=813"}],"version-history":[{"count":1,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/813\/revisions"}],"predecessor-version":[{"id":2928,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/813\/revisions\/2928"}],"wp:attachment":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/media?parent=813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/categories?post=813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/tags?post=813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}