{"id":799,"date":"2020-01-30T13:01:42","date_gmt":"2020-01-30T12:01:42","guid":{"rendered":"https:\/\/fcc-cornella.ccoo.cat\/?p=799"},"modified":"2021-12-01T20:47:08","modified_gmt":"2021-12-01T19:47:08","slug":"calcula-tu-nomina-desde-tu-movil","status":"publish","type":"post","link":"https:\/\/ccoo.app\/fcc-cornella\/calcula-tu-nomina-desde-tu-movil\/","title":{"rendered":"CALCULA TU N\u00d3MINA DESDE TU M\u00d3VIL"},"content":{"rendered":"<p>Ya ten\u00e9is disponible en a la APP, una nueva aplicaci\u00f3n que te ayudar\u00e1 a calcular tu nomina de este a\u00f1o desde tu m\u00f3vil: mucho m\u00e1s potente, r\u00e1pido y f\u00e1cil de usar, simplemente rellenado el formulario insertando tu categor\u00eda, tu fecha de antig\u00fcedad, el IRPF de tu \u00faltima nomina&#8230; y te dar\u00e1 como resultado: \u00a0sueldo mensual, las pagas y el premio de vacaciones de forma bruta y neta.<br \/>\nEsta herramienta te resultar\u00e1 muy \u00fatil con la cual podr\u00e1s consultar constantemente desde tu m\u00f3vil lo que cobraras y comp\u00e1rala con tu n\u00f3mina f\u00edsica.<br \/>\nNo dudes en utilizarla, para ello tendr\u00e9is que bajar la App de CCOO (pongo enlaces en la parte inferior) y registrase en ella como afiliados, \u00a0solo est\u00e1 disponible para afilados<\/p>\n<p>Que la Disfrutes!!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-790\" src=\"http:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/nomina2-138x300.jpg\" alt=\"\" width=\"138\" height=\"300\" srcset=\"https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/nomina2-138x300.jpg 138w, https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/nomina2-473x1024.jpg 473w, https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/nomina2-768x1664.jpg 768w, https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/nomina2-709x1536.jpg 709w, https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/nomina2-945x2048.jpg 945w, https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/nomina2.jpg 1080w\" sizes=\"auto, (max-width: 138px) 100vw, 138px\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-794\" src=\"http:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/calculo-138x300.jpg\" alt=\"\" width=\"138\" height=\"300\" srcset=\"https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/calculo-138x300.jpg 138w, https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/calculo-473x1024.jpg 473w, https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/calculo-768x1664.jpg 768w, https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/calculo-709x1536.jpg 709w, https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/calculo-945x2048.jpg 945w, https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/calculo.jpg 1080w\" sizes=\"auto, (max-width: 138px) 100vw, 138px\" \/><\/p>\n<p><span style=\"font-size: 24pt\"><span style=\"color: #0000ff\"><span style=\"color: #00ccff\"><span style=\"font-size: 18pt\">Descargar la Aplicacion aqu\u00ed<\/span> \u00a0\u00a0 \u00a0<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=cat.ccoo.mobile.carnet\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-586\" style=\"line-height: 1.5\" src=\"http:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2018\/09\/android.jpg\" alt=\"\" width=\"89\" height=\"74\" \/><\/a><\/span><\/span><\/span>\u00a0 \u00a0<a href=\"https:\/\/itunes.apple.com\/es\/app\/ccoo-cat\/id987915336?mt=8\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-587\" style=\"line-height: 1.5\" src=\"http:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2018\/09\/appel.jpg\" alt=\"\" width=\"109\" height=\"78\" \/><\/a>    \t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya ten\u00e9is disponible en a la APP, una nueva aplicaci\u00f3n que te ayudar\u00e1 a calcular tu nomina de este a\u00f1o desde tu m\u00f3vil: mucho m\u00e1s potente, r\u00e1pido y f\u00e1cil de &#8230; <a title=\"CALCULA TU N\u00d3MINA DESDE TU M\u00d3VIL\" class=\"read-more\" href=\"https:\/\/ccoo.app\/fcc-cornella\/calcula-tu-nomina-desde-tu-movil\/\" aria-label=\"Leer m\u00e1s sobre CALCULA TU N\u00d3MINA DESDE TU M\u00d3VIL\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5217,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-799","post","type-post","status-publish","format-standard","hentry","category-fccinfo","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"_links":{"self":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/users\/5217"}],"replies":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/comments?post=799"}],"version-history":[{"count":2,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/799\/revisions"}],"predecessor-version":[{"id":3194,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/799\/revisions\/3194"}],"wp:attachment":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/media?parent=799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/categories?post=799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/tags?post=799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}