{"id":782,"date":"2019-12-19T21:34:49","date_gmt":"2019-12-19T20:34:49","guid":{"rendered":"https:\/\/fcc-cornella.ccoo.cat\/?p=782"},"modified":"2021-12-01T20:47:09","modified_gmt":"2021-12-01T19:47:09","slug":"cierre-de-la-nomina-de-diciembre","status":"publish","type":"post","link":"https:\/\/ccoo.app\/fcc-cornella\/cierre-de-la-nomina-de-diciembre\/","title":{"rendered":"CIERRE DE LA NOMINA DE DICIEMBRE"},"content":{"rendered":"<p>Nos han informado que el cierre de la n\u00f3mina de este mes se realiza el d\u00eda 13 por motivos de las fiestas navide\u00f1as. Tenerlo en cuenta lo que realiz\u00e1is diferencias de servicios. \u00a0Este mes se prev\u00e9 que ingresen la n\u00f3mina de diciembre para el d\u00eda 20<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-676 alignright\" src=\"http:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2019\/04\/logo-de-cornella-app.jpg\" alt=\"\" width=\"54\" height=\"55\" srcset=\"https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2019\/04\/logo-de-cornella-app.jpg 172w, https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2019\/04\/logo-de-cornella-app-150x150.jpg 150w\" sizes=\"auto, (max-width: 54px) 100vw, 54px\" \/>    \t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos han informado que el cierre de la n\u00f3mina de este mes se realiza el d\u00eda 13 por motivos de las fiestas navide\u00f1as. Tenerlo en cuenta lo que realiz\u00e1is diferencias &#8230; <a title=\"CIERRE DE LA NOMINA DE DICIEMBRE\" class=\"read-more\" href=\"https:\/\/ccoo.app\/fcc-cornella\/cierre-de-la-nomina-de-diciembre\/\" aria-label=\"Leer m\u00e1s sobre CIERRE DE LA NOMINA DE DICIEMBRE\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5217,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-782","post","type-post","status-publish","format-standard","hentry","category-tablon","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"_links":{"self":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/users\/5217"}],"replies":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/comments?post=782"}],"version-history":[{"count":1,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/782\/revisions"}],"predecessor-version":[{"id":2933,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/782\/revisions\/2933"}],"wp:attachment":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/media?parent=782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/categories?post=782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/tags?post=782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}