{"id":695,"date":"2019-05-16T21:10:43","date_gmt":"2019-05-16T19:10:43","guid":{"rendered":"https:\/\/fcc-cornella.ccoo.cat\/?p=695"},"modified":"2021-12-01T20:47:17","modified_gmt":"2021-12-01T19:47:17","slug":"comunicado","status":"publish","type":"post","link":"https:\/\/ccoo.app\/fcc-cornella\/comunicado\/","title":{"rendered":"Comunicado"},"content":{"rendered":"<p>El lunes 20 de Mayo a las 14 horas, se celebrar\u00e1 una asamblea de trabajadores en las instalaciones de la empresa (C\/Progreso) para tratar los siguientes temas:<\/p>\n<p>&#8211; Negociaci\u00f3n sobre el Convenio.<\/p>\n<p>Se pide la m\u00e1xima asistencia por la importancia de los temas a tratar.<\/p>\n<p>El Comit\u00e9    \t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El lunes 20 de Mayo a las 14 horas, se celebrar\u00e1 una asamblea de trabajadores en las instalaciones de la empresa (C\/Progreso) para tratar los siguientes temas: &#8211; Negociaci\u00f3n sobre &#8230; <a title=\"Comunicado\" class=\"read-more\" href=\"https:\/\/ccoo.app\/fcc-cornella\/comunicado\/\" aria-label=\"Leer m\u00e1s sobre Comunicado\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5217,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-695","post","type-post","status-publish","format-standard","hentry","category-fccinfo","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"_links":{"self":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/users\/5217"}],"replies":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/comments?post=695"}],"version-history":[{"count":1,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/695\/revisions"}],"predecessor-version":[{"id":2948,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/695\/revisions\/2948"}],"wp:attachment":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/media?parent=695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/categories?post=695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/tags?post=695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}