{"id":3101,"date":"2022-05-03T13:04:26","date_gmt":"2022-05-03T11:04:26","guid":{"rendered":"https:\/\/ccoo.app\/fcc-cornella\/?p=3101"},"modified":"2022-05-03T13:04:27","modified_gmt":"2022-05-03T11:04:27","slug":"solicitud-a-la-empresa-formacion-de-carnet-c","status":"publish","type":"post","link":"https:\/\/ccoo.app\/fcc-cornella\/solicitud-a-la-empresa-formacion-de-carnet-c\/","title":{"rendered":"Solicitud a la empresa-Formaci\u00f3n de carnet C"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/cropped-logos-cornella-trasmparente-1-1.png\" alt=\"Cropped Logos Cornella Trasmparente 1.png\" class=\"wp-image-2853\" width=\"86\" height=\"86\" srcset=\"https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/cropped-logos-cornella-trasmparente-1-1.png 512w, https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/cropped-logos-cornella-trasmparente-1-1-300x300.png 300w, https:\/\/ccoo.app\/fcc-cornella\/wp-content\/blogs.dir\/6\/files\/sites\/138\/2020\/01\/cropped-logos-cornella-trasmparente-1-1-150x150.png 150w\" sizes=\"auto, (max-width: 86px) 100vw, 86px\" \/><\/figure><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Os comunicamos que ayer se le solicit\u00f3 a la empresa por escrito que nos indicara la fecha de inicio para la formacion de la obtencion del carnet C. Con el fin de que comience lo antes posible esta formacion este a\u00f1o.<\/p>\n\n\n\n<p>El comite<\/p>\n\n\n\n<p>Puedes descargar el escrito\u00a0\u00a0<a href=\"https:\/\/drive.google.com\/file\/d\/1uS7k-sufNHj1EjevcUn2LKemWh_OU9V9\/view?usp=sharing\" target=\"_blank\" aria-label=\" (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"ek-link\"><strong>___EN ESTA PAGINA___<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os comunicamos que ayer se le solicit\u00f3 a la empresa por escrito que nos indicara la fecha de inicio para la formacion de la obtencion del carnet C. Con el &#8230; <a title=\"Solicitud a la empresa-Formaci\u00f3n de carnet C\" class=\"read-more\" href=\"https:\/\/ccoo.app\/fcc-cornella\/solicitud-a-la-empresa-formacion-de-carnet-c\/\" aria-label=\"Leer m\u00e1s sobre Solicitud a la empresa-Formaci\u00f3n de carnet C\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5217,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,24],"tags":[],"class_list":["post-3101","post","type-post","status-publish","format-standard","hentry","category-tablon","category-app-push-fcccornella","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"_links":{"self":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/3101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/users\/5217"}],"replies":[{"embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/comments?post=3101"}],"version-history":[{"count":2,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/3101\/revisions"}],"predecessor-version":[{"id":3103,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/posts\/3101\/revisions\/3103"}],"wp:attachment":[{"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/media?parent=3101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/categories?post=3101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccoo.app\/fcc-cornella\/wp-json\/wp\/v2\/tags?post=3101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}