{"id":17467,"date":"2026-04-30T09:20:00","date_gmt":"2026-04-30T07:20:00","guid":{"rendered":"https:\/\/ccoo.app\/ajuntamentbarcelona\/?p=17467"},"modified":"2026-04-29T14:26:22","modified_gmt":"2026-04-29T12:26:22","slug":"seccio-sindical-de-ccoo-a-lajuntament-de-barcelona-28-dabril-de-2026","status":"publish","type":"post","link":"https:\/\/ccoo.app\/ajuntamentbarcelona\/seccio-sindical-de-ccoo-a-lajuntament-de-barcelona-28-dabril-de-2026\/","title":{"rendered":"Secci\u00f3 sindical de CCOO a l\u2019Ajuntament de Barcelona 28 d\u2019abril de 2026"},"content":{"rendered":"\n<p><strong>\u2261 COMUNICAT SINDICAL \u2261<\/strong><\/p>\n\n\n\n<p><strong>MESA GENERAL I COMISSI\u00d3 DE SEGUIMENT<\/strong><\/p>\n\n\n\n<p>Us informem que ja s\u2019ha publicat el calendari orientatiu 2026-2032 a la intranet municipal, a l\u2019apartat d\u2019Oficina d\u2019Atenci\u00f3 al Personal \/ Selecci\u00f3 i Provisi\u00f3.<\/p>\n\n\n\n<p><strong>Aquest calendari inclou fites importants, aconseguides per CCOO i altres sindicats signants, a l\u2019Acord de Condicions 2025-2028 com:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La Promoci\u00f3 Interna de 400 places en categories generals (convocat\u00f2ria febrer 2027).<\/li>\n\n\n\n<li>Enquesta per distribuir les 400 places de Promoci\u00f3 Interna (juny \u2013 molt important respondre).<\/li>\n\n\n\n<li>La Promoci\u00f3 Interna de C2 a C1 de GUB (convocat\u00f2ria octubre 2026).<\/li>\n\n\n\n<li>La Promoci\u00f3 Interna dels llocs a extingir cap a Grup B, C2 o C1 (convocat\u00f2ria juny 2026).<\/li>\n\n\n\n<li>Mobilitat al sector no uniformat de manera estable (a partir de juny 2027).<\/li>\n<\/ul>\n\n\n\n<p><strong>Altres temes importants i respostes:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Al maig es revisaran les bases de promocions internes a Grup B, E-C2 i C2 a C1 (xofers).<\/li>\n\n\n\n<li>Hem demanat convocar conjuntament les 400 places + 150 del 2029 (de moment rebutjat).<\/li>\n\n\n\n<li>Sobre C2 a C1 de GUB: s\u2019est\u00e0 treballant perqu\u00e8 hi pugui accedir tothom alhora.<\/li>\n\n\n\n<li>Revisi\u00f3 de places amb alta temporalitat i categories a extingir (modificaci\u00f3 prevista juny 2026).<\/li>\n\n\n\n<li>S\u2019inclour\u00e0 per\u00edode de vig\u00e8ncia als temaris.<\/li>\n\n\n\n<li>S\u2019estudia eliminar la mobilitat restringida a l\u2019equip central dels CSS.<\/li>\n\n\n\n<li>Al maig de 2027 es publicaran les bases de 27 places d\u2019Ajudant de Serveis Auxiliars.<\/li>\n<\/ul>\n\n\n\n<figure class=\"gb-block-image gb-block-image-c3d892d2\"><img loading=\"lazy\" decoding=\"async\" width=\"1076\" height=\"716\" class=\"gb-image gb-image-c3d892d2\" src=\"http:\/\/ccoo.app\/ajuntamentbarcelona\/wp-content\/blogs.dir\/6\/files\/sites\/228\/2026\/04\/calendario_abril_ccoo.png\" alt=\"\" title=\"calendario_abril_ccoo\" srcset=\"https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-content\/blogs.dir\/6\/files\/sites\/228\/2026\/04\/calendario_abril_ccoo.png 1076w, https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-content\/blogs.dir\/6\/files\/sites\/228\/2026\/04\/calendario_abril_ccoo-300x200.png 300w, https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-content\/blogs.dir\/6\/files\/sites\/228\/2026\/04\/calendario_abril_ccoo-1024x681.png 1024w, https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-content\/blogs.dir\/6\/files\/sites\/228\/2026\/04\/calendario_abril_ccoo-768x511.png 768w\" sizes=\"auto, (max-width: 1076px) 100vw, 1076px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Proc\u00e9s extraordinari de regularitzaci\u00f3 \u2013 mesures adoptades:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Enviament d\u2019informes de vulnerabilitat i volants de padr\u00f3 per SMS, correu i postal.<\/li>\n\n\n\n<li>Assignaci\u00f3 de cites per franges hor\u00e0ries.<\/li>\n\n\n\n<li>Habilitaci\u00f3 d\u2019un cinqu\u00e8 punt d\u2019atenci\u00f3.<\/li>\n\n\n\n<li>Entre 60 i 70 persones extres (pendent confirmaci\u00f3 exacta).<\/li>\n\n\n\n<li>Contractaci\u00f3 del servei de traducci\u00f3 en curs.<\/li>\n<\/ul>\n\n\n\n<p><strong>Qu\u00e8 hem demanat des de CCOO:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Millor previsi\u00f3.<\/li>\n\n\n\n<li>Millores urgents dels sistemes inform\u00e0tics.<\/li>\n\n\n\n<li>Respecte dels horaris del personal.<\/li>\n\n\n\n<li>Rebuig a externalitzacions i demanda de m\u00e9s personal estructural.<\/li>\n<\/ul>\n\n\n\n<p><strong>Comissi\u00f3 de seguiment:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Proposta del Pla de relleu en estudi.<\/li>\n\n\n\n<li>Adaptaci\u00f3 de l\u2019horari del CDIAP en exploraci\u00f3.<\/li>\n<\/ul>\n\n\n\n<p><strong>Secci\u00f3 sindical de CCOO a l\u2019Ajuntament de Barcelona<\/strong><br>ccooajtbcn@ccoo.cat \u2013 933018867 \u2013 @ccooajtbcn<br>Av. Francesc Camb\u00f3 17, 5a planta B \u00b7 Barcelona<\/p>\n\n\n\n<p><strong>\u2261 GENT COM TU MILLORA EL M\u00d3N! \u2261<\/strong><\/p>\n\n\n\n<p><strong>Tens cap dubte?<\/strong><br>Contacta amb nosaltres: ccooajtbcn@ccoo.cat<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2261 COMUNICAT SINDICAL \u2261 MESA GENERAL I COMISSI\u00d3 DE SEGUIMENT Us informem que ja s\u2019ha publicat el calendari orientatiu 2026-2032 a la intranet municipal, a l\u2019apartat d\u2019Oficina d\u2019Atenci\u00f3 al Personal &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Secci\u00f3 sindical de CCOO a l\u2019Ajuntament de Barcelona 28 d\u2019abril de 2026\" class=\"read-more button\" href=\"https:\/\/ccoo.app\/ajuntamentbarcelona\/seccio-sindical-de-ccoo-a-lajuntament-de-barcelona-28-dabril-de-2026\/#more-17467\" aria-label=\"M\u00e9s informaci\u00f3 sobre Secci\u00f3 sindical de CCOO a l\u2019Ajuntament de Barcelona 28 d\u2019abril de 2026\">Llegeix-ne m\u00e9s \u00bb<\/a><\/p>\n","protected":false},"author":97130,"featured_media":17468,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[304],"tags":[],"class_list":["post-17467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ajuntament","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"_links":{"self":[{"href":"https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-json\/wp\/v2\/posts\/17467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-json\/wp\/v2\/users\/97130"}],"replies":[{"embeddable":true,"href":"https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-json\/wp\/v2\/comments?post=17467"}],"version-history":[{"count":1,"href":"https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-json\/wp\/v2\/posts\/17467\/revisions"}],"predecessor-version":[{"id":17469,"href":"https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-json\/wp\/v2\/posts\/17467\/revisions\/17469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-json\/wp\/v2\/media\/17468"}],"wp:attachment":[{"href":"https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-json\/wp\/v2\/media?parent=17467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-json\/wp\/v2\/categories?post=17467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccoo.app\/ajuntamentbarcelona\/wp-json\/wp\/v2\/tags?post=17467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}